{"id":20449,"date":"2025-12-14T07:13:03","date_gmt":"2025-12-14T07:13:03","guid":{"rendered":"https:\/\/www.eifaschool.com\/?p=20449"},"modified":"2025-12-14T07:35:08","modified_gmt":"2025-12-14T07:35:08","slug":"anansi-laraignee","status":"publish","type":"post","link":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/","title":{"rendered":"Anansi l&rsquo;araign\u00e9e"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20449\" class=\"elementor elementor-20449\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa8bf13 e-flex e-con-boxed e-con e-parent\" data-id=\"aa8bf13\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8242f67 elementor-widget elementor-widget-text-editor\" data-id=\"8242f67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb, un conte bien-aim\u00e9 du Ghana mettant en sc\u00e8ne une araign\u00e9e malicieuse qui use de ruse pour jouer des tours aux autres animaux.<\/p>\n<p>De retour en classe, les enfants ont lu diff\u00e9rentes versions d\u2019histoires d\u2019Anansi et ont r\u00e9alis\u00e9 un exercice d\u2019\u00e9criture cr\u00e9ative sur ce personnage.<\/p>\n<p>Les \u00e9l\u00e8ves de CP pr\u00e9parent maintenant leur propre pi\u00e8ce de th\u00e9\u00e2tre sur Anansi, qu\u2019ils pr\u00e9senteront \u00e0 leurs parents !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c23d8eb elementor-widget elementor-widget-image-gallery\" data-id=\"c23d8eb\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-20449 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un groupe d&#039;enfants et plusieurs adultes posent et sourient ensemble \u00e0 l&#039;ext\u00e9rieur d&#039;un b\u00e2timent portant une enseigne rose vif. Les enfants portent des vestes et des sacs \u00e0 dos, et certains sont accroupis devant, tandis que d&#039;autres se tiennent derri\u00e8re.\" data-elementor-lightbox-description=\"EIFA Un groupe d&#039;enfants et plusieurs adultes posent et sourient ensemble \u00e0 l&#039;ext\u00e9rieur d&#039;un b\u00e2timent portant une enseigne rose vif. Les enfants portent des vestes et des sacs \u00e0 dos, et certains sont accroupis devant, tandis que d&#039;autres se tiennent derri\u00e8re.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MTksInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS0xMy5qcGciLCJzbGlkZXNob3ciOiJjMjNkOGViIn0%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13-1024x735.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un groupe d&#039;enfants et plusieurs adultes posent et sourient ensemble \u00e0 l&#039;ext\u00e9rieur d&#039;un b\u00e2timent portant une enseigne rose vif. Les enfants portent des vestes et des sacs \u00e0 dos, et certains sont accroupis devant, tandis que d&#039;autres se tiennent derri\u00e8re.\" aria-describedby=\"gallery-1-20419\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13-1024x735.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13-768x551.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-13.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20419'>\n\t\t\t\tEIFA Un groupe d&rsquo;enfants et plusieurs adultes posent et sourient ensemble \u00e0 l&rsquo;ext\u00e9rieur d&rsquo;un b\u00e2timent portant une enseigne rose vif. Les enfants portent des vestes et des sacs \u00e0 dos, et certains sont accroupis devant, tandis que d&rsquo;autres se tiennent derri\u00e8re.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Une table color\u00e9e recouverte d&#039;un tissu aux motifs \u00e9clatants pr\u00e9sente divers livres pour enfants et un puzzle repr\u00e9sentant une carte du Ghana, avec des titres comme &quot;Anansi l&#039;araign\u00e9e&quot; et &quot;Anansi et le manguier&quot;.\" data-elementor-lightbox-description=\"EIFA Une table color\u00e9e recouverte d&#039;un tissu aux motifs \u00e9clatants pr\u00e9sente divers livres pour enfants et un puzzle repr\u00e9sentant une carte du Ghana, avec des titres comme &quot;Anansi l&#039;araign\u00e9e&quot; et &quot;Anansi et le manguier&quot;.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzOTksInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS0zLmpwZyIsInNsaWRlc2hvdyI6ImMyM2Q4ZWIifQ%3D%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3.jpg'><img decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3-1024x734.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Une table color\u00e9e recouverte d&#039;un tissu aux motifs \u00e9clatants pr\u00e9sente divers livres pour enfants et un puzzle repr\u00e9sentant une carte du Ghana, avec des titres comme &quot;Anansi l&#039;araign\u00e9e&quot; et &quot;Anansi et le manguier&quot;.\" aria-describedby=\"gallery-1-20399\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3-1024x734.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3-768x550.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-3.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20399'>\n\t\t\t\tEIFA Une table color\u00e9e recouverte d&rsquo;un tissu aux motifs \u00e9clatants pr\u00e9sente divers livres pour enfants et un puzzle repr\u00e9sentant une carte du Ghana, avec des titres comme \u00ab\u00a0Anansi l&rsquo;araign\u00e9e\u00a0\u00bb et \u00ab\u00a0Anansi et le manguier\u00a0\u00bb.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un groupe d&#039;enfants et d&#039;adultes pose pour une photo en plein air pr\u00e8s du Tower Bridge \u00e0 Londres. Les enfants sont assis et debout, souriant \u00e0 l&#039;appareil photo, avec des b\u00e2timents modernes et le pont embl\u00e9matique en arri\u00e8re-plan.\" data-elementor-lightbox-description=\"EIFA Un groupe d&#039;enfants et d&#039;adultes pose pour une photo en plein air pr\u00e8s du Tower Bridge \u00e0 Londres. Les enfants sont assis et debout, souriant \u00e0 l&#039;appareil photo, avec des b\u00e2timents modernes et le pont embl\u00e9matique en arri\u00e8re-plan.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MTcsInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS0xMi5qcGciLCJzbGlkZXNob3ciOiJjMjNkOGViIn0%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12.jpg'><img decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12-1024x735.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un groupe d&#039;enfants et d&#039;adultes pose pour une photo en plein air pr\u00e8s du Tower Bridge \u00e0 Londres. Les enfants sont assis et debout, souriant \u00e0 l&#039;appareil photo, avec des b\u00e2timents modernes et le pont embl\u00e9matique en arri\u00e8re-plan.\" aria-describedby=\"gallery-1-20417\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12-1024x735.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12-768x551.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-12.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20417'>\n\t\t\t\tEIFA Un groupe d&rsquo;enfants et d&rsquo;adultes pose pour une photo en plein air pr\u00e8s du Tower Bridge \u00e0 Londres. Les enfants sont assis et debout, souriant \u00e0 l&rsquo;appareil photo, avec des b\u00e2timents modernes et le pont embl\u00e9matique en arri\u00e8re-plan.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un panneau fait \u00e0 la main, sur lequel on peut lire Welcome to the Anansi Show avec des lettres color\u00e9es et des gribouillis en forme de feuilles, est coll\u00e9 sur une porte en bois pr\u00e8s d&#039;une plaque intitul\u00e9e ASSEMBLY ROOM (salle d&#039;assembl\u00e9e).\" data-elementor-lightbox-description=\"EIFA Un panneau fait \u00e0 la main, sur lequel on peut lire Welcome to the Anansi Show avec des lettres color\u00e9es et des gribouillis en forme de feuilles, est coll\u00e9 sur une porte en bois pr\u00e8s d&#039;une plaque intitul\u00e9e ASSEMBLY ROOM (salle d&#039;assembl\u00e9e).\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MDksInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS04LmpwZyIsInNsaWRlc2hvdyI6ImMyM2Q4ZWIifQ%3D%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"462\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8-1024x739.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un panneau fait \u00e0 la main, sur lequel on peut lire Welcome to the Anansi Show avec des lettres color\u00e9es et des gribouillis en forme de feuilles, est coll\u00e9 sur une porte en bois pr\u00e8s d&#039;une plaque intitul\u00e9e ASSEMBLY ROOM (salle d&#039;assembl\u00e9e).\" aria-describedby=\"gallery-1-20409\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8-1024x739.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8-300x216.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8-768x554.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-8.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20409'>\n\t\t\t\tEIFA Un panneau fait \u00e0 la main, sur lequel on peut lire Welcome to the Anansi Show avec des lettres color\u00e9es et des gribouillis en forme de feuilles, est coll\u00e9 sur une porte en bois pr\u00e8s d&rsquo;une plaque intitul\u00e9e ASSEMBLY ROOM (salle d&rsquo;assembl\u00e9e).\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Deux jeunes enfants se tiennent devant une image d&#039;histoire projet\u00e9e dans une salle de classe. L&#039;un d&#039;eux tient un livre et lit, tandis que l&#039;autre porte un masque d&#039;animal. Un tapis d&#039;alphabet est pos\u00e9 sur le sol devant eux.\" data-elementor-lightbox-description=\"EIFA Deux jeunes enfants se tiennent devant une image d&#039;histoire projet\u00e9e dans une salle de classe. L&#039;un d&#039;eux tient un livre et lit, tandis que l&#039;autre porte un masque d&#039;animal. Un tapis d&#039;alphabet est pos\u00e9 sur le sol devant eux.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MDEsInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS00LmpwZyIsInNsaWRlc2hvdyI6ImMyM2Q4ZWIifQ%3D%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4-1024x734.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Deux jeunes enfants se tiennent devant une image d&#039;histoire projet\u00e9e dans une salle de classe. L&#039;un d&#039;eux tient un livre et lit, tandis que l&#039;autre porte un masque d&#039;animal. Un tapis d&#039;alphabet est pos\u00e9 sur le sol devant eux.\" aria-describedby=\"gallery-1-20401\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4-1024x734.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4-768x550.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-4.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20401'>\n\t\t\t\tEIFA Deux jeunes enfants se tiennent devant une image d&rsquo;histoire projet\u00e9e dans une salle de classe. L&rsquo;un d&rsquo;eux tient un livre et lit, tandis que l&rsquo;autre porte un masque d&rsquo;animal. Un tapis d&rsquo;alphabet est pos\u00e9 sur le sol devant eux.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un groupe d&#039;enfants est assis sur des nattes vertes dans une pi\u00e8ce faiblement \u00e9clair\u00e9e au sol rouge\u00e2tre, face \u00e0 une source de lumi\u00e8re vive. Certains enfants regardent la cam\u00e9ra, tandis que d&#039;autres parlent ou jouent entre eux.\" data-elementor-lightbox-description=\"EIFA Un groupe d&#039;enfants est assis sur des nattes vertes dans une pi\u00e8ce faiblement \u00e9clair\u00e9e au sol rouge\u00e2tre, face \u00e0 une source de lumi\u00e8re vive. Certains enfants regardent la cam\u00e9ra, tandis que d&#039;autres parlent ou jouent entre eux.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MjEsInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS0xNC5qcGciLCJzbGlkZXNob3ciOiJjMjNkOGViIn0%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14-1024x735.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un groupe d&#039;enfants est assis sur des nattes vertes dans une pi\u00e8ce faiblement \u00e9clair\u00e9e au sol rouge\u00e2tre, face \u00e0 une source de lumi\u00e8re vive. Certains enfants regardent la cam\u00e9ra, tandis que d&#039;autres parlent ou jouent entre eux.\" aria-describedby=\"gallery-1-20421\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14-1024x735.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14-768x551.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-14.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20421'>\n\t\t\t\tEIFA Un groupe d&rsquo;enfants est assis sur des nattes vertes dans une pi\u00e8ce faiblement \u00e9clair\u00e9e au sol rouge\u00e2tre, face \u00e0 une source de lumi\u00e8re vive. Certains enfants regardent la cam\u00e9ra, tandis que d&rsquo;autres parlent ou jouent entre eux.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un jeune enfant se tient devant un public assis, tenant un livre ouvert et lisant. Plusieurs enfants sont assis sur un tapis d&#039;alphabet, tandis que des adultes les observent depuis des chaises plac\u00e9es contre le mur d&#039;une salle de classe bien \u00e9clair\u00e9e.\" data-elementor-lightbox-description=\"EIFA Un jeune enfant se tient devant un public assis, tenant un livre ouvert et lisant. Plusieurs enfants sont assis sur un tapis d&#039;alphabet, tandis que des adultes les observent depuis des chaises plac\u00e9es contre le mur d&#039;une salle de classe bien \u00e9clair\u00e9e.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MDcsInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS03LmpwZyIsInNsaWRlc2hvdyI6ImMyM2Q4ZWIifQ%3D%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7-1024x734.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un jeune enfant se tient devant un public assis, tenant un livre ouvert et lisant. Plusieurs enfants sont assis sur un tapis d&#039;alphabet, tandis que des adultes les observent depuis des chaises plac\u00e9es contre le mur d&#039;une salle de classe bien \u00e9clair\u00e9e.\" aria-describedby=\"gallery-1-20407\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7-1024x734.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7-768x550.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-7.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20407'>\n\t\t\t\tEIFA Un jeune enfant se tient devant un public assis, tenant un livre ouvert et lisant. Plusieurs enfants sont assis sur un tapis d&rsquo;alphabet, tandis que des adultes les observent depuis des chaises plac\u00e9es contre le mur d&rsquo;une salle de classe bien \u00e9clair\u00e9e.\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c23d8eb\" data-elementor-lightbox-title=\"EIFA Un groupe d&#039;enfants et quelques adultes sont assis autour de tables dans une salle de classe moderne et lumineuse dot\u00e9e de grandes fen\u00eatres. Certains enfants sourient \u00e0 la cam\u00e9ra, tandis que d&#039;autres parlent ou travaillent \u00e0 des activit\u00e9s. Des formes color\u00e9es d\u00e9corent le sol.\" data-elementor-lightbox-description=\"EIFA Un groupe d&#039;enfants et quelques adultes sont assis autour de tables dans une salle de classe moderne et lumineuse dot\u00e9e de grandes fen\u00eatres. Certains enfants sourient \u00e0 la cam\u00e9ra, tandis que d&#039;autres parlent ou travaillent \u00e0 des activit\u00e9s. Des formes color\u00e9es d\u00e9corent le sol.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjA0MjMsInVybCI6Imh0dHBzOlwvXC93d3cuZWlmYXNjaG9vbC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcL0FuYW5zaS0xLmpwZyIsInNsaWRlc2hvdyI6ImMyM2Q4ZWIifQ%3D%3D\" href='https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"459\" src=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1-1024x735.jpg\" class=\"attachment-large size-large\" alt=\"EIFA Un groupe d&#039;enfants et quelques adultes sont assis autour de tables dans une salle de classe moderne et lumineuse dot\u00e9e de grandes fen\u00eatres. Certains enfants sourient \u00e0 la cam\u00e9ra, tandis que d&#039;autres parlent ou travaillent \u00e0 des activit\u00e9s. Des formes color\u00e9es d\u00e9corent le sol.\" aria-describedby=\"gallery-1-20423\" srcset=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1-1024x735.jpg 1024w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1-300x215.jpg 300w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1-768x551.jpg 768w, https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-1.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-20423'>\n\t\t\t\tEIFA Un groupe d&rsquo;enfants et quelques adultes sont assis autour de tables dans une salle de classe moderne et lumineuse dot\u00e9e de grandes fen\u00eatres. Certains enfants sourient \u00e0 la cam\u00e9ra, tandis que d&rsquo;autres parlent ou travaillent \u00e0 des activit\u00e9s. Des formes color\u00e9es d\u00e9corent le sol.\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb, un conte bien-aim\u00e9 du Ghana mettant en sc\u00e8ne une araign\u00e9e malicieuse qui use de ruse pour jouer des tours aux autres animaux. <\/p>\n","protected":false},"author":3,"featured_media":20403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"class_list":["post-20449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anansi l&#039;araign\u00e9e - EIFA International School (EIFA)<\/title>\n<meta name=\"description\" content=\"Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anansi l&#039;araign\u00e9e\" \/>\n<meta property=\"og:description\" content=\"C\u2019est la rentr\u00e9e \u00e0 l\u2019EIFA. L\u2019\u00e9cole a repris vie aujourd\u2019hui dans les \u00e9clats de rire, les cahiers tout neufs et les retrouvailles entre amis apr\u00e8s les vacances. Place aux nouveaux projets, aux d\u00e9couvertes et \u00e0 un trimestre plein d\u2019\u00e9nergie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/\" \/>\n<meta property=\"og:site_name\" content=\"EIFA International School (EIFA)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eifainternationalschoollondon\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-14T07:13:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-14T07:35:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Kadri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Kadri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/\"},\"author\":{\"name\":\"Thomas Kadri\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#\\\/schema\\\/person\\\/db8afbc0c66dd2490511ff9376a6dac9\"},\"headline\":\"Anansi l&rsquo;araign\u00e9e\",\"datePublished\":\"2025-12-14T07:13:03+00:00\",\"dateModified\":\"2025-12-14T07:35:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/Anansi-5.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/\",\"url\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/\",\"name\":\"Anansi l'araign\u00e9e - EIFA International School (EIFA)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/Anansi-5.jpg\",\"datePublished\":\"2025-12-14T07:13:03+00:00\",\"dateModified\":\"2025-12-14T07:35:08+00:00\",\"description\":\"Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/Anansi-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/Anansi-5.jpg\",\"width\":1080,\"height\":774,\"caption\":\"EIFA Cinq enfants portant des masques et des costumes d'animaux sont debout sur un tapis alphab\u00e9tique color\u00e9 et posent pour une photo. Derri\u00e8re eux se trouve une projection d'animaux de la jungle. Un autre enfant arrose une plante sur la droite. Des accessoires et des paniers sont pos\u00e9s sur le sol.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/anansi-laraignee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anansi l&#8217;araign\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/\",\"name\":\"EIFA International School (EIFA)\",\"description\":\"A bilingual international school for young citizens of the world\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#organization\",\"name\":\"EIFA International School (EIFA)\",\"url\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/eifa_logo_white.png\",\"contentUrl\":\"https:\\\/\\\/www.eifaschool.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/eifa_logo_white.png\",\"width\":500,\"height\":231,\"caption\":\"EIFA International School (EIFA)\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eifainternationalschoollondon\",\"https:\\\/\\\/www.instagram.com\\\/eifainternationalschool\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZ7MJ5WK69Dpi8spXepJv2Q\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eifa-international-school\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eifaschool.com\\\/fr\\\/#\\\/schema\\\/person\\\/db8afbc0c66dd2490511ff9376a6dac9\",\"name\":\"Thomas Kadri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g\",\"caption\":\"Thomas Kadri\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anansi l'araign\u00e9e - EIFA International School (EIFA)","description":"Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/","og_locale":"fr_FR","og_type":"article","og_title":"Anansi l'araign\u00e9e","og_description":"C\u2019est la rentr\u00e9e \u00e0 l\u2019EIFA. L\u2019\u00e9cole a repris vie aujourd\u2019hui dans les \u00e9clats de rire, les cahiers tout neufs et les retrouvailles entre amis apr\u00e8s les vacances. Place aux nouveaux projets, aux d\u00e9couvertes et \u00e0 un trimestre plein d\u2019\u00e9nergie.","og_url":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/","og_site_name":"EIFA International School (EIFA)","article_publisher":"https:\/\/www.facebook.com\/eifainternationalschoollondon","article_published_time":"2025-12-14T07:13:03+00:00","article_modified_time":"2025-12-14T07:35:08+00:00","og_image":[{"width":1080,"height":774,"url":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg","type":"image\/jpeg"}],"author":"Thomas Kadri","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Thomas Kadri","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#article","isPartOf":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/"},"author":{"name":"Thomas Kadri","@id":"https:\/\/www.eifaschool.com\/fr\/#\/schema\/person\/db8afbc0c66dd2490511ff9376a6dac9"},"headline":"Anansi l&rsquo;araign\u00e9e","datePublished":"2025-12-14T07:13:03+00:00","dateModified":"2025-12-14T07:35:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/"},"wordCount":471,"publisher":{"@id":"https:\/\/www.eifaschool.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg","articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/","url":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/","name":"Anansi l'araign\u00e9e - EIFA International School (EIFA)","isPartOf":{"@id":"https:\/\/www.eifaschool.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#primaryimage"},"image":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg","datePublished":"2025-12-14T07:13:03+00:00","dateModified":"2025-12-14T07:35:08+00:00","description":"Ce mois-ci, les \u00e9l\u00e8ves de GS et CP \u00e9tudient les contes traditionnels. Nous avons visit\u00e9 le Unicorn Theatre pour voir \u00ab Anansi l\u2019araign\u00e9e \u00bb.","breadcrumb":{"@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#primaryimage","url":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg","contentUrl":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/Anansi-5.jpg","width":1080,"height":774,"caption":"EIFA Cinq enfants portant des masques et des costumes d'animaux sont debout sur un tapis alphab\u00e9tique color\u00e9 et posent pour une photo. Derri\u00e8re eux se trouve une projection d'animaux de la jungle. Un autre enfant arrose une plante sur la droite. Des accessoires et des paniers sont pos\u00e9s sur le sol."},{"@type":"BreadcrumbList","@id":"https:\/\/www.eifaschool.com\/fr\/anansi-laraignee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eifaschool.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Anansi l&#8217;araign\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.eifaschool.com\/fr\/#website","url":"https:\/\/www.eifaschool.com\/fr\/","name":"EIFA International School (EIFA)","description":"A bilingual international school for young citizens of the world","publisher":{"@id":"https:\/\/www.eifaschool.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eifaschool.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eifaschool.com\/fr\/#organization","name":"EIFA International School (EIFA)","url":"https:\/\/www.eifaschool.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eifaschool.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/2024\/05\/eifa_logo_white.png","contentUrl":"https:\/\/www.eifaschool.com\/wp-content\/uploads\/2024\/05\/eifa_logo_white.png","width":500,"height":231,"caption":"EIFA International School (EIFA)"},"image":{"@id":"https:\/\/www.eifaschool.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eifainternationalschoollondon","https:\/\/www.instagram.com\/eifainternationalschool","https:\/\/www.youtube.com\/channel\/UCZ7MJ5WK69Dpi8spXepJv2Q","https:\/\/www.linkedin.com\/company\/eifa-international-school\/"]},{"@type":"Person","@id":"https:\/\/www.eifaschool.com\/fr\/#\/schema\/person\/db8afbc0c66dd2490511ff9376a6dac9","name":"Thomas Kadri","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c77470483cf02a47048b571cf698fdcd0fed33b87c8b506923412c1949b72127?s=96&d=mm&r=g","caption":"Thomas Kadri"}}]}},"_links":{"self":[{"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/posts\/20449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/comments?post=20449"}],"version-history":[{"count":4,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/posts\/20449\/revisions"}],"predecessor-version":[{"id":20466,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/posts\/20449\/revisions\/20466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/media\/20403"}],"wp:attachment":[{"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/media?parent=20449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/categories?post=20449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eifaschool.com\/fr\/wp-json\/wp\/v2\/tags?post=20449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}